{"id":19,"date":"2021-02-07T17:16:05","date_gmt":"2021-02-07T16:16:05","guid":{"rendered":"https:\/\/marketing.stratoflights.com\/?page_id=19"},"modified":"2025-11-21T22:26:19","modified_gmt":"2025-11-21T21:26:19","slug":"portfolio","status":"publish","type":"page","link":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/","title":{"rendered":"Unser Portfolio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unser Portfolio - Stratoflights<\/title>\n<meta name=\"description\" content=\"Werfen Sie einen Blick auf einige unserer Produktionen. Wetterballonprojekte als au\u00dfergew\u00f6hnliche Filmproduktion. Lassen Sie sich inspirieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marketing.stratoflights.com\/de\/portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unser Portfolio - Stratoflights\" \/>\n<meta property=\"og:description\" content=\"Werfen Sie einen Blick auf einige unserer Produktionen. Wetterballonprojekte als au\u00dfergew\u00f6hnliche Filmproduktion. Lassen Sie sich inspirieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marketing.stratoflights.com\/de\/portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Stratoflights\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T21:26:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/portfolio\\\/\",\"url\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/portfolio\\\/\",\"name\":\"Unser Portfolio - Stratoflights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/#website\"},\"datePublished\":\"2021-02-07T16:16:05+00:00\",\"dateModified\":\"2025-11-21T21:26:19+00:00\",\"description\":\"Werfen Sie einen Blick auf einige unserer Produktionen. Wetterballonprojekte als au\u00dfergew\u00f6hnliche Filmproduktion. Lassen Sie sich inspirieren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/portfolio\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/portfolio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/portfolio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Portfolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/\",\"name\":\"Stratoflights\",\"description\":\"Eine weitere WordPress-Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marketing.stratoflights.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unser Portfolio - Stratoflights","description":"Werfen Sie einen Blick auf einige unserer Produktionen. Wetterballonprojekte als au\u00dfergew\u00f6hnliche Filmproduktion. Lassen Sie sich inspirieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/","og_locale":"de_DE","og_type":"article","og_title":"Unser Portfolio - Stratoflights","og_description":"Werfen Sie einen Blick auf einige unserer Produktionen. Wetterballonprojekte als au\u00dfergew\u00f6hnliche Filmproduktion. Lassen Sie sich inspirieren.","og_url":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/","og_site_name":"Stratoflights","article_modified_time":"2025-11-21T21:26:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/","url":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/","name":"Unser Portfolio - Stratoflights","isPartOf":{"@id":"https:\/\/marketing.stratoflights.com\/de\/#website"},"datePublished":"2021-02-07T16:16:05+00:00","dateModified":"2025-11-21T21:26:19+00:00","description":"Werfen Sie einen Blick auf einige unserer Produktionen. Wetterballonprojekte als au\u00dfergew\u00f6hnliche Filmproduktion. Lassen Sie sich inspirieren.","breadcrumb":{"@id":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marketing.stratoflights.com\/de\/portfolio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/marketing.stratoflights.com\/de\/portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/marketing.stratoflights.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unser Portfolio"}]},{"@type":"WebSite","@id":"https:\/\/marketing.stratoflights.com\/de\/#website","url":"https:\/\/marketing.stratoflights.com\/de\/","name":"Stratoflights","description":"Eine weitere WordPress-Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marketing.stratoflights.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":3,"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":585,"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/pages\/19\/revisions\/585"}],"wp:attachment":[{"href":"https:\/\/marketing.stratoflights.com\/de\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}